{"id":27,"date":"2018-07-31T17:35:20","date_gmt":"2018-07-31T17:35:20","guid":{"rendered":"http:\/\/jobster.local\/search-jobs\/"},"modified":"2018-07-31T17:35:20","modified_gmt":"2018-07-31T17:35:20","slug":"search-jobs","status":"publish","type":"page","link":"https:\/\/old.badiofreelance.com\/nl\/search-jobs\/","title":{"rendered":"Search Jobs"},"content":{"rendered":"<style id=\"kb-rowlayout_9f71a8-f7\">#kt-layout-id_9f71a8-f7{margin-top:0px;margin-bottom:0px;}#kt-layout-id_9f71a8-f7 > .kt-row-column-wrap{padding-top:0px;padding-bottom:0px;padding-left:0px;padding-right:0px;}<\/style>\n<div class=\"wp-block-kadence-rowlayout alignwide\"><div id=\"kt-layout-id_9f71a8-f7\" class=\"kt-row-layout-inner kt-layout-id_9f71a8-f7\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-gutter-default kt-v-gutter-default kt-row-valign-top kt-row-layout-equal kt-tab-layout-inherit kt-m-colapse-left-to-right kt-mobile-layout-row\">\n<div class=\"wp-block-kadence-column inner-column-1 kadence-column_d03ee0-6f\"><div class=\"kt-inside-inner-col\"><style id=\"kb-rowlayout_4daf89-66\">#kt-layout-id_4daf89-66{margin-top:0px;margin-bottom:0px;}#kt-layout-id_4daf89-66 > .kt-row-column-wrap{padding-top:0px;padding-bottom:0px;padding-left:0px;padding-right:0px;}<\/style>\n<div class=\"wp-block-kadence-rowlayout alignwide\"><div id=\"kt-layout-id_4daf89-66\" class=\"kt-row-layout-inner kt-layout-id_4daf89-66\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-gutter-default kt-v-gutter-default kt-row-valign-top kt-row-layout-equal kt-tab-layout-inherit kt-m-colapse-left-to-right kt-mobile-layout-row\">\n<div class=\"wp-block-kadence-column inner-column-1 kadence-column_0e7cd0-5e\"><div class=\"kt-inside-inner-col\">\n\n\n\n<h1 class=\"kt-adv-heading_75ba68-951 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading_75ba68-951\">Geavanceerd zoeken naar vacatures<\/h1>\n<\/div><\/div>\n<\/div><\/div><\/div>\n\n\n<style id=\"kb-rowlayout_bb8b60-ec\">#kt-layout-id_bb8b60-ec{margin-top:15px;}#kt-layout-id_bb8b60-ec > .kt-row-column-wrap{padding-top:0px;padding-bottom:0px;padding-left:0px;padding-right:0px;}<\/style>\n<div class=\"wp-block-kadence-rowlayout alignwide category-description-row-wrapper\"><div id=\"kt-layout-id_bb8b60-ec\" class=\"kt-row-layout-inner kt-layout-id_bb8b60-ec\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-gutter-default kt-v-gutter-default kt-row-valign-top kt-row-layout-equal kt-tab-layout-inherit kt-m-colapse-left-to-right kt-mobile-layout-row\">\n<div class=\"wp-block-kadence-column inner-column-1 kadence-column_eb3805-ec\"><div class=\"kt-inside-inner-col\"><style>.category-description-row-wrapper{display:none;}<\/style>\n<\/div><\/div>\n<\/div><\/div><\/div>\n\n\n<style id=\"kb-rowlayout_2abfd9-51\">#kt-layout-id_2abfd9-51{margin-top:15px;margin-bottom:0px;}#kt-layout-id_2abfd9-51 > .kt-row-column-wrap{padding-top:0px;padding-bottom:0px;padding-left:0px;padding-right:0px;}<\/style>\n<div class=\"wp-block-kadence-rowlayout alignwide subcategories-row-wrapper\"><div id=\"kt-layout-id_2abfd9-51\" class=\"kt-row-layout-inner kt-layout-id_2abfd9-51\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-gutter-default kt-v-gutter-default kt-row-valign-top kt-row-layout-equal kt-tab-layout-inherit kt-m-colapse-left-to-right kt-mobile-layout-row\">\n<div class=\"wp-block-kadence-column inner-column-1 kadence-column_1cc47e-39\"><div class=\"kt-inside-inner-col\"><style>.subcategories-row-wrapper{display:none;}<\/style>\n<\/div><\/div>\n<\/div><\/div><\/div>\n\n\n<style id=\"kb-rowlayout_8aeab7-b7\">#kt-layout-id_8aeab7-b7{margin-top:30px;margin-bottom:0px;}#kt-layout-id_8aeab7-b7 > .kt-row-column-wrap{padding-top:0px;padding-bottom:0px;padding-left:0px;padding-right:0px;}<\/style>\n<div class=\"wp-block-kadence-rowlayout alignwide\"><div id=\"kt-layout-id_8aeab7-b7\" class=\"kt-row-layout-inner kt-layout-id_8aeab7-b7\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-gutter-default kt-v-gutter-default kt-row-valign-top kt-row-layout-equal kt-tab-layout-inherit kt-m-colapse-left-to-right kt-mobile-layout-row\">\n<div class=\"wp-block-kadence-column inner-column-1 kadence-column_5d9ccb-88\"><div class=\"kt-inside-inner-col\"><div class=\"full-width-search-form-wrapper\">\n\n\t<form method=\"get\" class=\"ui form filter-container js-job-filter-form\" action=\"https:\/\/old.badiofreelance.com\/nl\/search-jobs\/\" data-trp-original-action=\"https:\/\/old.badiofreelance.com\/nl\/search-jobs\/\">\n\n\t\t<div class=\"ui grid stackable doubling five column row\">\n\n\t\t\t<!-- Term -->\n\t\t\t\n\t\t\t\t<div class=\"column computer-hidden\">\n\n\t\t\t\t\t<div class=\"field\">\n\t\t\t\t\t\t<div class=\"ui right labeled input\">\n\t\t\t\t\t\t\t<input type=\"text\" placeholder=\"Search Term\" value=\"\" name=\"term\" \/>\n\t\t\t\t\t\t\t<div class=\"ui label filter-box\"><i class=\"filter icon mr0\"><\/i><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"column mobile-hidden\">\n\n\t\t\t\t\t<div class=\"field\">\n\t\t\t\t\t\t<div class=\"ui clearable left icon input\">\n\t\t\t\t\t\t\t<input type=\"text\" placeholder=\"Search Term\" value=\"\" name=\"term\" \/>\n\t\t\t\t\t\t\t<i class=\"search icon\"><\/i>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t<\/div>\n\n\t\t\t\n\t\t\t<!-- Location -->\n\t\t\t\n\t\t\t\t<div class=\"column\">\n\n\t\t\t\t\t<div class=\"field\">\n\t\t\t\t\t\t<div class=\"ui search js-location-autocomplete\">\n\t\t\t\t\t\t\t<div class=\"ui left icon clearable input\">\n\t\t\t\t\t\t\t\t<input class=\"prompt fw400 ten wide column\" type=\"text\" data-replaceplaceholder=\"Select a valid location\" placeholder=\"Location\" id=\"location_input\" value=\"\" name=\"location\">\n\t\t\t\t\t\t\t\t<input id=\"lat\" type=\"hidden\" name=\"latitude\" value=\"\">\n\t\t\t\t\t\t\t\t<input id=\"long\" type=\"hidden\" name=\"longitude\" value=\"\">\n\t\t\t\t\t\t\t\t<i class=\"map marker alternate icon\"><\/i>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"results\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t<\/div>\n\n\t\t\t\t<!-- Radius -->\n\t\t\t\t\n\t\t\t\t\t<div class=\"column\">\n\n\t\t\t\t\t\t<div class=\"field\">\n\t\t\t\t\t\t\t<div class=\"ui left icon clearable input\">\n\t\t\t\t\t\t\t\t<input class=\"fw400\" type=\"text\" data-replaceplaceholder=\"Insert a valid number\" data-replaceplaceholder2=\"Select a location first\" placeholder=\"Radius (miles)\" id=\"location_input_radius\" value=\"\" name=\"radius\">\n\n\t\t\t\t\t\t\t\t<i class=\"location arrow icon\"><\/i>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\n\t\t\t<!-- Categories -->\n\t\t\t\n\t\t\t\t<div class=\"column js-group-filters collapse-filters\">\n\n\t\t\t\t\t<div class=\"field\">\n\n\t\t\t\t\t\t<select name=\"category\" class=\"ui selection fluid search full-text-search dropdown clearable\" id=\"\" >\n\n\t\n\t\t<option value=\"\">Categories<\/option>\n\n\t\n\t\t\t<option   value=\"business\">Bedrijf<\/option>\n\n\t\t\t\n\t\t\t\t\t<option   value=\"business-consulting\">&nbsp;\u2023 Bedrijfsconsulting<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"business-plans\">&nbsp;\u2023 Bedrijfsplannen<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"career-counseling\">&nbsp;\u2023 Loopbaanbegeleiding<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"crm-management\">&nbsp;\u2023 CRM-beheer<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"customer-care\">&nbsp;\u2023 Klantenservice<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"e-commerce-management\">&nbsp;\u2023 Beheer van e-commerce<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"erp-management\">&nbsp;\u2023 ERP Beheer<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"event-management\">&nbsp;\u2023 Evenementmanagement<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"financial-consulting\">&nbsp;\u2023 Financieel advies<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"game-concept-design\">&nbsp;\u2023 Gameconceptontwerp<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"hr-consulting\">&nbsp;\u2023 HR-advies<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"legal-consulting\">&nbsp;\u2023 Juridisch advies<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"market-research\">&nbsp;\u2023 Marktonderzoek<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"other-business\">&nbsp;\u2023 Ander<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"presentations\">&nbsp;\u2023 Presentaties<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"project-management\">&nbsp;\u2023 Project management<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"sales\">&nbsp;\u2023 Verkoop<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"supply-chain-management\">&nbsp;\u2023 Voorraadketenbeheer<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"virtual-assistant\">&nbsp;\u2023 Virtuele assistent<\/option>\n\n\t\t\t\t\t\n\t\t\t<option   value=\"data\">Gegevens<\/option>\n\n\t\t\t\n\t\t\t\t\t<option   value=\"cloud-based-solutions\">&nbsp;\u2023 Cloudgebaseerde oplossingen<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"data-analytics\">&nbsp;\u2023 Gegevensanalyse<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"data-processing-automations\">&nbsp;\u2023 Gegevensverwerking Automatiseringen<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"data-processing-consultation\">&nbsp;\u2023 Consultatie gegevensverwerking<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"data-science-consulting\">&nbsp;\u2023 Consultancy op het gebied van datawetenschap<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"data-science-ranking\">&nbsp;\u2023 Datawetenschap ranking<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"data-visualization\">&nbsp;\u2023 Data visualisatie<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"data-visualization-graphs\">&nbsp;\u2023 Grafieken voor gegevensvisualisatie<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"database-administration\">&nbsp;\u2023 Database administratie<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"database-consulting\">&nbsp;\u2023 Database-advies<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"database-queries\">&nbsp;\u2023 Databasevragen<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"geographic-information-systems\">&nbsp;\u2023 Geografische Informatie Systemen<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"machine-learning\">&nbsp;\u2023Machinaal leren<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"oracle-apex\">&nbsp;\u2023Oracle Apex<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"other-data\">&nbsp;\u2023 Ander<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"time-series-analysis\">&nbsp;\u2023 Tijdreeksanalyse<\/option>\n\n\t\t\t\t\t\n\t\t\t<option   value=\"digital-marketing\">Digitale marketing<\/option>\n\n\t\t\t\n\t\t\t\t\t<option   value=\"affiliate-marketing\">&nbsp;\u2023 Affiliate Marketing<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"book-ebook-marketing\">&nbsp;\u2023 Boek- en e-bookmarketing<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"community-management\">&nbsp;\u2023 Gemeenschap beheer<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"crowdfunding\">&nbsp;\u2023 Crowdfunding<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"display-advertising\">&nbsp;\u2023 Display-advertenties<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"e-commerce-marketing\">&nbsp;\u2023 E-commercemarketing<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"email-marketing\">&nbsp;\u2023 Email reclame<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"guest-posting\">&nbsp;\u2023 Gastpost<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"influencer-marketing\">&nbsp;\u2023 Influencermarketing<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"local-seo\">&nbsp;\u2023 Lokale SEO<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"marketing-advice\">&nbsp;\u2023Marketingadvies<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"marketing-strategy\">&nbsp;\u2023 Marketingstrategie<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"mobile-app-marketing\">&nbsp;\u2023Marketing voor mobiele apps<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"music-promotion\">&nbsp;\u2023Muziekpromotie<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"podcast-marketing\">&nbsp;\u2023 Podcastmarketing<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"public-relations\">&nbsp;\u2023 Publieke relaties<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"search-engine-marketing-sem\">&nbsp;\u2023 Zoekmachinemarketing (SEM)<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"search-engine-optimization-seo\">&nbsp;\u2023 Zoekmachineoptimalisatie (SEO)<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"social-media-advertising\">&nbsp;\u2023 Adverteren op sociale media<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"social-media-marketing\">&nbsp;\u2023 Sociale media marketing<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"text-message-marketing\">&nbsp;\u2023Sms-marketing<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"video-marketing\">&nbsp;\u2023Videomarketing<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"web-analytics\">&nbsp;\u2023 Web analyses<\/option>\n\n\t\t\t\t\t\n\t\t\t<option   value=\"graphics-design\">Grafisch design<\/option>\n\n\t\t\t\n\t\t\t\t\t<option   value=\"album-cover-design\">&nbsp;\u2023 Ontwerp van albumomslag<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"app-design\">&nbsp;\u2023 App-ontwerp<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"architecture-interior-design\">&nbsp;\u2023 Architectuur en interieurontwerp<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"book-design\">&nbsp;\u2023 Boekontwerp<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"brand-style-guides\">&nbsp;\u2023 Merkstijlgidsen<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"brochure-design\">&nbsp;\u2023 Brochure ontwerp<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"building-engineering\">&nbsp;\u2023 Bouwkunde<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"building-information-modeling\">&nbsp;\u2023 Modellering van bouwinformatie<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"business-cards-stationery\">&nbsp;\u2023 Visitekaartjes en briefpapier<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"car-wraps\">&nbsp;\u2023 Car Wraps<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"cartoons-comics\">&nbsp;\u2023 Cartoons en strips<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"catalog-design\">&nbsp;\u2023 Catalogusontwerp<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"character-modeling\">&nbsp;\u2023 Karaktermodellering<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"email-design\">&nbsp;\u2023 E-mailontwerp<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"fashion-design\">&nbsp;\u2023Modeontwerp<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"flyer-design\">&nbsp;\u2023 Flyerontwerp<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"fonts-typography\">&nbsp;\u2023 Lettertypen en typografie<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"game-art\">&nbsp;\u2023 Spelkunst<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"graphics-for-streamers\">&nbsp;\u2023 Afbeeldingen voor streamers<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"icon-design\">&nbsp;\u2023 Icoonontwerp<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"illustration\">&nbsp;\u2023 Illustratie<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"image-editing\">&nbsp;\u2023 Foto bewerken<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"industrial-product-design\">&nbsp;\u2023 Industrieel en productontwerp<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"infographic-design\">&nbsp;\u2023Infografische ontwerp<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"invitation-design\">&nbsp;\u2023 Uitnodigingsontwerp<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"jewelry-design\">&nbsp;\u2023 Sieraden Ontwerp<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"landing-page-design\">&nbsp;\u2023 Ontwerp van bestemmingspagina<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"landscape-design\">&nbsp;\u2023 Landschapsontwerp<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"logo-design\">&nbsp;\u2023 Logo ontwerp<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"menu-design\">&nbsp;\u2023 Menu-ontwerp<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"nft-art\">&nbsp;\u2023 NFT-kunst<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"pattern-design\">&nbsp;\u2023 Patroonontwerp<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"podcast-cover-art\">&nbsp;\u2023 Podcast-omslagafbeeldingen<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"portraits-caricatures\">&nbsp;\u2023 Portretten &amp; Karikaturen<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"poster-design\">&nbsp;\u2023 Posterontwerp<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"presentation-design\">&nbsp;\u2023 Presentatie Ontwerp<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"resume-design\">&nbsp;\u2023 Ontwerp hervatten<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"signage-design\">&nbsp;\u2023 Bewegwijzering Ontwerp<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"social-media-design\">&nbsp;\u2023 Ontwerp van sociale media<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"storyboards\">&nbsp;\u2023 Storyboards<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"t-shirts-merchandise\">&nbsp;\u2023 T-Shirts &amp; Merchandise<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"tattoo-design\">&nbsp;\u2023 Tatoeage Ontwerp<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"trade-booth-design\">&nbsp;\u2023 Ontwerp van handelsstand<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"twitch-store\">&nbsp;\u2023 Twitch Store<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"ux-design\">&nbsp;\u2023 UX-ontwerp<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"vector-tracing\">&nbsp;\u2023 Vectortracering<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"web-banners\">&nbsp;\u2023Webbanners<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"website-design\">&nbsp;\u2023 Website ontwerp<\/option>\n\n\t\t\t\t\t\n\t\t\t<option   value=\"in-demand-services\">Veelgevraagde diensten<\/option>\n\n\t\t\t\n\t\t\t\t\t<option   value=\"car-wash\">&nbsp;\u2023 Carwash<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"carpet-cleaning\">&nbsp;\u2023 Tapijt schoonmaken<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"deep-cleaning\">&nbsp;\u2023 Grondige reiniging<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"delivery\">&nbsp;\u2023 Levering<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"door-fitting\">&nbsp;\u2023 Deurbeslag<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"fence-gate-installation\">&nbsp;\u2023 Installatie van hek en poort<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"flat-pack-furniture-assembly\">&nbsp;\u2023 Flat pack meubelmontage<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"handyman\">&nbsp;\u2023 Klusjesman<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"house-cleaning\">&nbsp;\u2023 Huis schoonmaken<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"mechanic\">&nbsp;\u2023 Monteur<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"other-in-demand-services\">&nbsp;\u2023 Ander<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"painting-decoration\">&nbsp;\u2023 Schilderen &amp; Decoratie<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"pest-control\">&nbsp;\u2023 Ongediertebestrijding<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"taxi-driver\">&nbsp;\u2023 Taxi chauffeur<\/option>\n\n\t\t\t\t\t\n\t\t\t<option   value=\"lifestyle\">levensstijl<\/option>\n\n\t\t\t\n\t\t\t\t\t<option   value=\"arts-crafts\">&nbsp;\u2023Kunst &amp; Ambachten<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"astrology-psychics\">&nbsp;\u2023 Astrologie en helderzienden<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"collectibles\">&nbsp;\u2023 Verzamelobjecten<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"family-genealogy\">&nbsp;\u2023 Familie &amp; Genealogie<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"food-and-beverage\">&nbsp;\u2023Eten en drinken<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"gaming\">&nbsp;\u2023 Gamen<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"greeting-cards-videos\">&nbsp;\u2023 Wenskaarten en video&#039;s<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"life-coaching\">&nbsp;\u2023 Levens begeleiding<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"modeling-acting\">&nbsp;\u2023 Modelleren en acteren<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"other-lifestyle\">&nbsp;\u2023 Ander<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"personal-stylists\">&nbsp;\u2023 Persoonlijke stylisten<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"puzzle-game-creation\">&nbsp;\u2023 Puzzel- en spelcreatie<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"traveling\">&nbsp;\u2023 Reizend<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"wellness\">&nbsp;\u2023 Welzijn<\/option>\n\n\t\t\t\t\t\n\t\t\t<option   value=\"music-audio\">Muziek en audio<\/option>\n\n\t\t\t\n\t\t\t\t\t<option   value=\"audio-ads-production\">&nbsp;\u2023 Productie van audioadvertenties<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"audio-editing\">&nbsp;\u2023 Audiobewerking<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"audio-logo-sonic-branding-other\">&nbsp;\u2023Audio Logo &amp; Sonic Branding Overig<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"audiobook-production\">&nbsp;\u2023 Audioboekproductie<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"beat-making\">&nbsp;\u2023 Beat maken<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"dj-drops-tags\">&nbsp;\u2023 DJ Drops &amp; Tags<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"dj-mixing\">&nbsp;\u2023 DJ-mixen<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"jingles-intros\">&nbsp;\u2023Jingles &amp; Intro&#039;s<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"meditation-music\">&nbsp;\u2023 Meditatie Muziek<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"mixing-mastering\">&nbsp;\u2023 Mixen &amp; Masteren<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"music-transcription\">&nbsp;\u2023Muziektranscriptie<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"online-music-lessons\">&nbsp;\u2023 Online muzieklessen<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"podcast-editing\">&nbsp;\u2023 Podcastbewerking<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"producers-composers\">&nbsp;\u2023 Producenten en componisten<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"remixing-mashups\">&nbsp;\u2023 Remixen en mashups<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"session-musicians\">&nbsp;\u2023 Sessiemuzikanten<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"singers-vocalists\">&nbsp;\u2023Zangers &amp; Vocalisten<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"songwriters\">&nbsp;\u2023 songwriters<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"sound-design\">&nbsp;\u2023 Geluid design<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"synth-presets\">&nbsp;\u2023 Synth-voorinstellingen<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"vocal-tuning\">&nbsp;\u2023Vocal Tuning<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"voice-over\">&nbsp;\u2023 Voice over<\/option>\n\n\t\t\t\t\t\n\t\t\t<option   value=\"online-classes-teaching\">Online lessen en lesgeven<\/option>\n\n\t\t\t\n\t\t\t\t\t<option   value=\"coding-lessons\">&nbsp;\u2023 Codeerlessen<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"cooking-lessons\">&nbsp;\u2023 kooklessen<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"dancing-lessons\">&nbsp;\u2023 Danslessen<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"fitness-lessons\">&nbsp;\u2023Fitnesslessen<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"languages\">&nbsp;\u2023 Talen<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"music-and-instruments\">&nbsp;\u2023 Muziek en instrumenten<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"online-tutoring\">&nbsp;\u2023Online bijles<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"other-online-classes-teaching\">&nbsp;\u2023 Ander<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"science\">&nbsp;\u2023 Wetenschap<\/option>\n\n\t\t\t\t\t\n\t\t\t<option   value=\"other\">Ander<\/option>\n\n\t\t\t\n\t\t\t<option   value=\"programming-tech\">Programmering &amp; Techniek<\/option>\n\n\t\t\t\n\t\t\t\t\t<option   value=\"blockchain-cryptocurrency\">&nbsp;\u2023 Blockchain en cryptovaluta<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"chatbots\">&nbsp;\u2023 Chatbots<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"convert-files\">&nbsp;\u2023 Bestanden omzetten<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"cybersecurity-data-protection\">&nbsp;\u2023 Cyberbeveiliging en gegevensbescherming<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"data-engineering\">&nbsp;\u2023 Data-engineering<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"data-processing\">&nbsp;\u2023 Gegevensverwerking<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"data-science\">&nbsp;\u2023Gegevenswetenschap<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"databases\">&nbsp;\u2023 Databases<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"desktop-applications\">&nbsp;\u2023 Bureaubladtoepassingen<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"development-for-streamers\">&nbsp;\u2023 Ontwikkeling voor streamers<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"devops-cloud\">&nbsp;\u2023DevOps &amp; Cloud<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"e-commerce-development\">&nbsp;\u2023 Ontwikkeling van e-commerce<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"electronics-engineering\">&nbsp;\u2023 Elektronica Engineering<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"game-development\">&nbsp;\u2023 Spelontwikkeling<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"get-your-website-in-a-few-steps\">&nbsp;\u2023 Krijg uw website in een paar stappen<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"mobile-apps\">&nbsp;\u2023 Mobiele apps<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"nft-development\">&nbsp;\u2023NFT-ontwikkeling<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"online-coding-lessons\">&nbsp;\u2023 Online codeerlessen<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"other-programming-tech\">&nbsp;\u2023 Ander<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"qa-review\">&nbsp;\u2023 QA &amp; Review<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"support-it\">&nbsp;\u2023 Ondersteun het<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"user-testing\">&nbsp;\u2023 Gebruikerstests<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"web-programming\">&nbsp;\u2023 Webprogrammeren<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"website-builders-cms\">&nbsp;\u2023 Websitebouwers &amp; CMS<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"wordpress\">&nbsp;\u2023WordPress<\/option>\n\n\t\t\t\t\t\n\t\t\t<option   value=\"video-animation\">Video &amp; Animatie<\/option>\n\n\t\t\t\n\t\t\t\t\t<option   value=\"3d-product-animation\">&nbsp;\u2023 3D-productanimatie<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"animated-gifs\">&nbsp;\u2023 Geanimeerde GIF&#039;s<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"animation-for-kids\">&nbsp;\u2023 Animatie voor kinderen<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"animation-for-streamers\">&nbsp;\u2023 Animatie voor streamers<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"app-website-previews\">&nbsp;\u2023 App- en websitevoorbeelden<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"article-to-video\">&nbsp;\u2023 Artikel naar video<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"book-trailers\">&nbsp;\u2023 Boek trailers<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"character-animation\">&nbsp;\u2023 Karakteranimatie<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"corporate-videos\">&nbsp;\u2023 Bedrijfsvideo&#039;s<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"crowdfunding-videos\">&nbsp;\u2023 Crowdfundingvideo&#039;s<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"e-commerce-product-videos\">&nbsp;\u2023 E-commerce productvideo&#039;s<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"elearning-video-production\">&nbsp;\u2023 eLearning videoproductie<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"filmed-video-production\">&nbsp;\u2023Gefilmde videoproductie<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"game-trailers\">&nbsp;\u2023 Gametrailers<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"intro-outro-videos\">&nbsp;\u2023 Intro &amp; Outro-video&#039;s<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"live-action-explainers\">&nbsp;\u2023Live Action Explainers<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"local-photography\">&nbsp;\u2023 Lokale fotografie<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"logo-animation\">&nbsp;\u2023 Logo-animatie<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"lottie-web-animation\">&nbsp;\u2023 Lottie &amp; webanimatie<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"meditation-videos\">&nbsp;\u2023 Meditatievideo&#039;s<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"music-videos\">&nbsp;\u2023 Muziek video&#039;s<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"nft-animation\">&nbsp;\u2023 NFT-animatie<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"other-video-animation\">&nbsp;\u2023 Ander<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"product-photography\">&nbsp;\u2023Productfotografie<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"real-estate-promos\">&nbsp;\u2023 Vastgoedpromo&#039;s<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"screencasting-videos\">&nbsp;\u2023 Screencast-video&#039;s<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"slideshow-videos\">&nbsp;\u2023 Diavoorstelling Video&#039;s<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"social-media-videos\">&nbsp;\u2023 Video&#039;s op sociale media<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"spokesperson-videos\">&nbsp;\u2023 Woordvoerder Video&#039;s<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"subtitles-captions\">&nbsp;\u2023 Ondertitels en bijschriften<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"unboxing-videos\">&nbsp;\u2023 Video&#039;s uitpakken<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"video-ads-commercials\">&nbsp;\u2023 Videoadvertenties en commercials<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"video-editing\">&nbsp;\u2023 Video bewerking<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"video-templates-editing\">&nbsp;\u2023 Bewerken van videosjablonen<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"videographers\">&nbsp;\u2023 Videografen<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"visual-effects\">&nbsp;\u2023 Visuele effecten<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"whiteboard-animated-explainers\">&nbsp;\u2023 Whiteboard en geanimeerde uitleg<\/option>\n\n\t\t\t\t\t\n\t\t\t<option   value=\"writing-translation\">Schrijven en vertalen<\/option>\n\n\t\t\t\n\t\t\t\t\t<option   value=\"ad-copy\">&nbsp;\u2023 Advertentiekopie<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"articles-blog-posts\">&nbsp;\u2023 Artikelen en blogberichten<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"beta-reading\">&nbsp;\u2023 B\u00e8ta lezen<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"book-ebook-writing\">&nbsp;\u2023 Boeken en e-boeken schrijven<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"book-editing\">&nbsp;\u2023 Boek bewerken<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"brand-voice-tone\">&nbsp;\u2023 Merkstem &amp; toon<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"business-names-slogans\">&nbsp;\u2023Bedrijfsnamen en slogans<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"case-studies\">&nbsp;\u2023 Casestudy&#039;s<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"cover-letters\">&nbsp;\u2023 Sollicitatiebrieven<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"creative-writing\">&nbsp;\u2023 Creatief schrijven<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"elearning-content-development\">&nbsp;\u2023 eLearning-inhoudsontwikkeling<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"email-copy\">&nbsp;\u2023 E-mail kopi\u00ebren<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"grant-writing\">&nbsp;\u2023 Grant schrijven<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"job-descriptions\">&nbsp;\u2023 Werk omschrijving<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"linkedin-profiles\">&nbsp;\u2023 LinkedIn-profielen<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"podcast-writing\">&nbsp;\u2023 Podcast schrijven<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"press-releases\">&nbsp;\u2023 Persberichten<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"product-descriptions\">&nbsp;\u2023Productbeschrijvingen<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"proofreading-editing\">&nbsp;\u2023 Proeflezen en bewerken<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"research-summaries\">&nbsp;\u2023 Onderzoek en samenvattingen<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"resume-writing\">&nbsp;\u2023 Hervatten schrijven<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"sales-copy\">&nbsp;\u2023 Verkoopkopie<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"scriptwriting\">&nbsp;\u2023 Script schrijven<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"social-media-copy\">&nbsp;\u2023Sociale media kopi\u00ebren<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"speechwriting\">&nbsp;\u2023 Spraakschrijven<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"technical-writing\">&nbsp;\u2023 Technisch schrijven<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"transcription\">&nbsp;\u2023 Transcriptie<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"translation\">&nbsp;\u2023 Vertaling<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"ux-writing\">&nbsp;\u2023 UX-schrijven<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"website-content\">&nbsp;\u2023 Website inhoud<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option   value=\"white-papers\">&nbsp;\u2023 Witte papieren<\/option>\n\n\t\t\t\t\t\n<\/select>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t<\/div>\n\n\t\t\t\n\t\t\t<!-- Tags -->\n\t\t\t\n\t\t\t\t<div class=\"column js-group-filters collapse-filters\">\n\n\t\t\t\t\t<div class=\"field\">\n\t\t\t\t\t\t<select style=\"display: none;\" class=\"ui fluid search selection dropdown\" name=\"tag[]\" multiple=\"\">\n\t\t\t\t\t\t\t<option value=\"\">Tag<\/option>\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<option value=\"android\">android<\/option>\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<option value=\"apk\">APK<\/option>\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<option value=\"cab\">taxi<\/option>\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<option value=\"car\">auto<\/option>\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<option value=\"code\">code<\/option>\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<option value=\"delivery\">Levering<\/option>\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<option value=\"deploy\">inzetten<\/option>\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<option value=\"driver\">Bestuurder<\/option>\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<option value=\"ecommerce\">e-commerce<\/option>\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<option value=\"ecommerce-website\">e-commerce website<\/option>\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<option value=\"native\">oorspronkelijk<\/option>\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<option value=\"online-store\">online winkel<\/option>\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<option value=\"play\">Speel<\/option>\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<option value=\"product\">Product<\/option>\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<option value=\"publish\">publiceren<\/option>\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<option value=\"shop\">winkel<\/option>\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<option value=\"source\">bron<\/option>\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<option value=\"store\">op te slaan<\/option>\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<option value=\"taxi\">taxi<\/option>\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<option value=\"testing\">testen<\/option>\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<option value=\"this-i-s\">dit is<\/option>\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<option value=\"uber\">Uber<\/option>\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<option value=\"woocommerce\">WooCommerce<\/option>\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<option value=\"woocommerce-store\">woocommerce winkel<\/option>\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<option value=\"woocommerce-website\">woocommerce website<\/option>\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<option value=\"wordpress\">wordpress<\/option>\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<option value=\"wordpress-website\">wordpress website<\/option>\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/select>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t<\/div>\n\n\t\t\t\n\t\t\t<!-- Minimum Rating -->\n\t\t\t\n\t\t\t\t<div class=\"column js-group-filters collapse-filters\">\n\n\t\t\t\t\t<div class=\"field\">\n\t\t\t\t\t\t<select name=\"min_rating\" class=\"ui clearable dropdown\">\n\t\t\t\t\t\t\t<option value=\"\">Minimum Rating<\/option>\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<option  value=\"5\">5 Stars<\/option>\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<option  value=\"4\">4 Stars<\/option>\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<option  value=\"3\">3 Stars<\/option>\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<option  value=\"2\">2 Stars<\/option>\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<option  value=\"1\">1 Star<\/option>\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/select>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t<\/div>\n\n\t\t\t\n\t\t\t<!-- Price Type -->\n\t\t\t\n\t\t\t<!-- Price -->\n\t\t\t\n\t\t\t\t<div class=\"column js-group-filters collapse-filters\">\n\n\t\t\t\t\t<div class=\"two fields\">\n\n\t\t\t\t\t\t<!-- Price Min -->\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"field\">\n\t\t\t\t\t\t\t\t<div class=\"ui clearable input\">\n\t\t\t\t\t\t\t\t\t<input class=\"fw400\" type=\"text\" name=\"min_price\" placeholder=\"Min Price\" value=\"\" \/>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t\t<!-- Price Max -->\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"field\">\n\t\t\t\t\t\t\t\t<div class=\"ui clearable input\">\n\t\t\t\t\t\t\t\t\t<input class=\"fw400\" type=\"text\" name=\"max_price\" placeholder=\"Max Price\" value=\"\" \/>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<!-- Price Toggle -->\n\t\t\t\t\t\n\t\t\t\t<\/div>\n\n\t\t\t\n\t\t\t<!-- Deadline -->\n\t\t\t\n\t\t\t<!-- Date -->\n\t\t\t\n\t\t\t<!-- Action -->\n\t\t\t\n\t\t\t<!-- Delivery -->\n\t\t\t\n\t\t\t\t<div class=\"column js-group-filters collapse-filters\">\n\n\t\t\t\t\t<div class=\"field inline-field\">\n\t\t\t\t\t\t<label for=\"max-days-title\" class=\"label\">\n\n\t\t\t\t\t\t\tLevering\n\t\t\t\t\t\t\t<span id=\"amount-label\" class=\"small-label\">\n\n\t\t\t\t\t\t\t\t(days)\n\t\t\t\t\t\t\t<\/span>\n\n\t\t\t\t\t\t<\/label>\n\n\t\t\t\t\t\t<input type=\"text\" id=\"amount\" name=\"max_days\" readonly class=\"max-days-input\" value=\"30\" \/>\n\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<!-- Delivery Slider -->\n\t\t\t\t\t<div class=\"field\">\n\t\t\t\t\t\t<div id=\"slider-range-min\" data-value=\"30\"><\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<!-- Instant\/Empty Delivery -->\n\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"column js-group-filters collapse-filters\">\n\n\t\t\t\t\t\t\t<!-- Delivery Toggle -->\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<div class=\"field\">\n\t\t\t\t\t\t\t\t\t<div class=\"ui toggle checkbox inline-toggle\">\n\t\t\t\t\t\t\t\t\t\t<input type=\"checkbox\" name=\"without_delivery\" checked value=\"yes\" \/>\n\t\t\t\t\t\t\t\t\t\t<label>Include undefined delivery<\/label>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\n\t\t\t\t<\/div>\n\n\t\t\t\n\t\t\t<div class=\"column\">\n\n\t\t\t\t<!-- Action -->\n\t\t\t\t\n\t\t\t\t<!-- Filter Results Button -->\n\t\t\t\t<div class=\"field\">\n\t\t\t\t\t<input class=\"ui fluid primary button full-width no-margin bigger\" type=\"submit\" value=\"Filter Results\" name=\"research_me\" \/>\n\t\t\t\t<\/div>\n\n\t\t\t<\/div>\n\n\t\t<\/div>\n\n\t\t<!-- Switch to Filter -->\n\t\t\n\t<input type=\"hidden\" name=\"trp-form-language\" value=\"nl\"\/><\/form>\n\n<\/div>\n<\/div><\/div>\n<\/div><\/div><\/div>\n\n\n<style id=\"kb-rowlayout_6e505a-50\">#kt-layout-id_6e505a-50{margin-top:0px;margin-bottom:10px;}#kt-layout-id_6e505a-50 > .kt-row-column-wrap{padding-top:0px;padding-bottom:0px;padding-left:0px;padding-right:0px;}<\/style>\n<div class=\"wp-block-kadence-rowlayout alignwide\"><div id=\"kt-layout-id_6e505a-50\" class=\"kt-row-layout-inner kt-layout-id_6e505a-50\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-gutter-default kt-v-gutter-default kt-row-valign-middle kt-row-layout-equal kt-tab-layout-equal kt-m-colapse-left-to-right kt-mobile-layout-left-golden\">\n<div class=\"wp-block-kadence-column inner-column-1 kadence-column_4937f3-b8\"><div class=\"kt-inside-inner-col\"><div class=\"sort-by-section\">\n\n\t\n\t\t<div class=\"slim-dropdown-wrapper\">\n\n\t\t\t<label>Sort by<\/label>\n\n\t\n\t\t\t<select class=\"ui dropdown filter-results-by filter-job-results-by slim-dropdown\">\n\n\t\t\t\t\n\t\t\t\t<option  value=\"auto\">Auto<\/option>\n\t\t\t\t<option  value=\"new\">Newest<\/option>\n\t\t\t\t<option  value=\"old\">Oldest<\/option>\n\n\t\t\t\t\n\t\t\t\t\t<option  value=\"rating\">Rating<\/option>\n\t\t\t\t\t<option selected=\"selected\" value=\"reviews\">Reviews number<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t\t<option  value=\"views\">Views: most visits first<\/option>\n\n\t\t\t\t\t\n\t\t\t\t\t<option  value=\"price_lowest\">Price: lowest first<\/option>\n\t\t\t\t\t<option  value=\"price_highest\">Price: highest first<\/option>\n\n\t\t\t\t\n\t\t\t<\/select>\n\n\t\n\t\t<\/div>\n\n\t\n<\/div>\n<\/div><\/div>\n\n\n<style id=\"kb-column_3875f9-87\">.kadence-column_3875f9-87{text-align:right;}<\/style>\n<div class=\"wp-block-kadence-column inner-column-2 kadence-column_3875f9-87\"><div class=\"kt-inside-inner-col\"><div class=\"grid-switch-relative\">\n\n\t<ul class=\"listing-job\">\n\n\t\t<li class=\"layout_jobs\" data-value=\"grid\"><i class=\"grid layout icon\"><\/i><\/li>\n\n\t\t<li class=\"layout_jobs\" data-value=\"list\"><i class=\"list layout icon\"><\/i><\/li>\n\n\t<\/ul>\n\n<\/div>\n<\/div><\/div>\n<\/div><\/div><\/div>\n\n\n<style id=\"kb-rowlayout_b6903c-bc\">#kt-layout-id_b6903c-bc{margin-top:0px;margin-bottom:0px;}#kt-layout-id_b6903c-bc > .kt-row-column-wrap{padding-top:0px;padding-bottom:0px;padding-left:0px;padding-right:0px;}<\/style>\n<div class=\"wp-block-kadence-rowlayout alignwide\"><div id=\"kt-layout-id_b6903c-bc\" class=\"kt-row-layout-inner kt-layout-id_b6903c-bc\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-gutter-default kt-v-gutter-default kt-row-valign-top kt-row-layout-equal kt-tab-layout-inherit kt-m-colapse-left-to-right kt-mobile-layout-row\">\n<div class=\"wp-block-kadence-column inner-column-1 kadence-column_8e108a-32\"><div class=\"kt-inside-inner-col\"><div class=\"cf\" style=\"width:100%\">\n\n\t\n\t\t\t\t<div class=\"row special wpj-load-more-target cf  ui four cards\">\n\n\t\t\t\t\t<!-- Job Card -->\n<div class=\"job-card ui card wpj-card-style-3 extra-slider-height\">\n\n\t<!-- Job Image -->\n\t<div class=\"image\">\n\n\t\t<!-- Featured -->\n\t\t\n\t\t<!-- Show until slider, load then remove -->\n\t\t<div class=\"card-image-clipper\">\n\t\t\t<div class=\"card-image-helper\">\n\t\t\t\t<img class=\"card-blurry-bg\" src=\"https:\/\/old.badiofreelance.com\/wp-content\/uploads\/2022\/10\/27608ED1-BC16-4BD7-9D5C-79865AA5DA18.jpeg\" alt=\"24398Search Jobs\" \/>\n\t\t\t\t<img class=\"my_image\" src=\"https:\/\/old.badiofreelance.com\/wp-content\/uploads\/2022\/10\/27608ED1-BC16-4BD7-9D5C-79865AA5DA18.jpeg\" alt=\"24398Search Jobs\" \/>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t<!-- Show slider -->\n\t\t\n\t\t\t<div class=\"wpj-carousel owl-carousel owl-theme\">\n\n\t\t\t\t\n\t\t\t\t\t\t<a href=\"https:\/\/old.badiofreelance.com\/nl\/job\/in-demand-services\/i-will-be-your-taxi-driver\/\" class=\"slide-img\">\n\t\t\t\t\t\t\t<img src=\"https:\/\/old.badiofreelance.com\/wp-content\/uploads\/2022\/10\/27608ED1-BC16-4BD7-9D5C-79865AA5DA18-262x405.jpeg\" class=\"job-blurry-bg\" data-src=\"https:\/\/old.badiofreelance.com\/wp-content\/uploads\/2022\/10\/27608ED1-BC16-4BD7-9D5C-79865AA5DA18-262x405.jpeg\" \/>\n\t\t\t\t\t\t\t<img src=\"https:\/\/old.badiofreelance.com\/wp-content\/uploads\/2022\/10\/27608ED1-BC16-4BD7-9D5C-79865AA5DA18-262x405.jpeg\" class=\"\" data-src=\"https:\/\/old.badiofreelance.com\/wp-content\/uploads\/2022\/10\/27608ED1-BC16-4BD7-9D5C-79865AA5DA18-262x405.jpeg\" \/>\n\t\t\t\t\t\t<\/a>\n\n\t\t\t\t\t\t\n\t\t\t\t\t\t<a href=\"https:\/\/old.badiofreelance.com\/nl\/job\/in-demand-services\/i-will-be-your-taxi-driver\/\" class=\"slide-img\">\n\t\t\t\t\t\t\t<img src=\"https:\/\/old.badiofreelance.com\/wp-content\/themes\/wpjobster\/assets\/images\/media\/blank.gif\" class=\"job-blurry-bg bx-lazy owl-lazy\" data-src=\"https:\/\/old.badiofreelance.com\/wp-content\/uploads\/2022\/10\/B377F868-82F8-4379-B0D5-84C791F08132-262x405.jpeg\" \/>\n\t\t\t\t\t\t\t<img src=\"https:\/\/old.badiofreelance.com\/wp-content\/themes\/wpjobster\/assets\/images\/media\/blank.gif\" class=\"bx-lazy owl-lazy\" data-src=\"https:\/\/old.badiofreelance.com\/wp-content\/uploads\/2022\/10\/B377F868-82F8-4379-B0D5-84C791F08132-262x405.jpeg\" \/>\n\t\t\t\t\t\t<\/a>\n\n\t\t\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\n\t<\/div>\n\n\t<!-- User -->\n\t<div class=\"user-area\">\n\n\t\t<!-- User Avatar -->\n\t\t<div class=\"user-avatar\">\n\n\t\t\t\n\t<a class=\"pr user-avatar-image\" href=\"https:\/\/old.badiofreelance.com\/nl\/user\/sane\/\">\n\n\n\t\t<img class=\"round-avatar\" width=\"55\" height=\"55\" src=\"https:\/\/secure.gravatar.com\/avatar\/8b479b145456cdd2c9142341697dfda9?s=55&d=mm&r=g\" \/>\n\n\t\t\n\t<\/a>\n\n\n\t\t<\/div>\n\n\t\t<!-- Username & Level -->\n\t\t<div class=\"user-content\">\n\t\t\t<a href=\"https:\/\/old.badiofreelance.com\/nl\/user\/sane\/\" class=\"cards-user-link\">\n\n\t\t\t\t<!-- Name -->\n\t\t\t\t<div class=\"user-name\">verstandig<\/div>\n\n\t\t\t\t<!-- Level -->\n\t\t\t\t\n\t<span class=\"user-level-label user-level-label-0\">New Arrival<\/span>\n\n\n\t\t\t<\/a>\n\t\t<\/div>\n\n\t\t<!-- Rating after user details -->\n\t\t\n\t\t\t\t<div class=\"user-rating\">\n\n\t\t\t\t\t<div class=\"wpj-rating-single\">\n\n\t\t\t\t\t\t<i class=\"star icon static\"><\/i>\n\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t<span class=\"rating-score\"><strong>5.0<\/strong><\/span>\n\t\t\t\t\t\t\t<span class=\"rating-reviews-number\">(3)<\/span>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t<\/div>\n\n\t\t\t\n\t<\/div>\n\n\t<!-- Title -->\n\t<div class=\"job-area\">\n\t\t<a class=\"title list-header\" href=\"https:\/\/old.badiofreelance.com\/nl\/job\/in-demand-services\/i-will-be-your-taxi-driver\/\" title=\"\">Ik zal je taxichauffeur zijn<\/a>\n\n\t\t<div class=\"description visible-on-list\">\n\n\t\t\tDit is maar een test\n\t\t<\/div>\n\n\t\t<!-- Rating after title -->\n\t\t\n\t<\/div>\n\n\t<!-- Price & Let's Meet & Favorites -->\n\t<div class=\"job-bottom-info\">\n\t\t<div class=\"job-price-area\">\n\n\t\t\t<!-- Price -->\n\t\t\t<div class=\"job-price\">\n\n\t\t\t\t\n\t\t\t\t\t<div class=\"price-type\">milestone rate<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"price\">$20.00<\/div>\n\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\t<div class=\"card-icons one-item\">\n\t\t\n\t\t\t\t<!-- Instant Delivery -->\n\t\t\t\t\n\t\t\t\t<!-- Let's Meet -->\n\t\t\t\t\n\t\t\t\t\t<div class=\"job-lets-meet\" data-inverted=\"\" data-tooltip=\"Let's meet - New York\" data-position=\"top center\">\n\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t<i class=\"icon icon-img\"><img src=\"https:\/\/old.badiofreelance.com\/wp-content\/themes\/wpjobster\/assets\/images\/card\/location-icon.svg\" alt=\"\"><\/i>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\n\t\t\t\t<!-- Distance -->\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t<\/div>\n\n\t\t<!-- Favorites -->\n\t\t<div class=\"job-favorites\">\n\n\t\t\t<div data-inverted=\"\" data-tooltip=\"Favorites\" data-position=\"top center\">\n\n\t\t\t\t\n\t<div class=\"upb_add_remove_links\">\n\n\t\t<a href=\"https:\/\/old.badiofreelance.com\/nl\/authentication-login\/?redirect_to=https%3A%2F%2Fold.badiofreelance.com%2Fnl%2Fsearch-jobs%2F\" rel=\"24398\" class=\"login-link\">\n\t\t\t<div class=\"empty-heart\"><\/div>\n\t\t\t<span>\n\t\t\t\t<div class=\"\">\n\t\t\t\t\t<span><i class=\"heart outline grey icon\"><\/i><\/span>\n\t\t\t\t<\/div>\n\t\t\t<\/span>\n\t\t<\/a>\n\n\t<\/div>\n\n\n\t\t\t<\/div>\n\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><!-- Job Card -->\n<div class=\"job-card ui card wpj-card-style-3 extra-slider-height\">\n\n\t<!-- Job Image -->\n\t<div class=\"image\">\n\n\t\t<!-- Featured -->\n\t\t\n\t\t<!-- Show until slider, load then remove -->\n\t\t<div class=\"card-image-clipper\">\n\t\t\t<div class=\"card-image-helper\">\n\t\t\t\t<img class=\"card-blurry-bg\" src=\"https:\/\/old.badiofreelance.com\/wp-content\/uploads\/2022\/10\/Untitled-design-4.jpg\" alt=\"23628Search Jobs\" \/>\n\t\t\t\t<img class=\"my_image\" src=\"https:\/\/old.badiofreelance.com\/wp-content\/uploads\/2022\/10\/Untitled-design-4.jpg\" alt=\"23628Search Jobs\" \/>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t<!-- Show slider -->\n\t\t\n\t\t\t<div class=\"wpj-carousel owl-carousel owl-theme\">\n\n\t\t\t\t\n\t\t\t\t\t\t<a href=\"https:\/\/old.badiofreelance.com\/nl\/job\/programming-tech\/i-will-build-wordpress-ecommerce-website-using-woocommerce\/\" class=\"slide-img\">\n\t\t\t\t\t\t\t<img src=\"https:\/\/old.badiofreelance.com\/wp-content\/uploads\/2022\/10\/Untitled-design-4-720x405.jpg\" class=\"job-blurry-bg\" data-src=\"https:\/\/old.badiofreelance.com\/wp-content\/uploads\/2022\/10\/Untitled-design-4-720x405.jpg\" \/>\n\t\t\t\t\t\t\t<img src=\"https:\/\/old.badiofreelance.com\/wp-content\/uploads\/2022\/10\/Untitled-design-4-720x405.jpg\" class=\"\" data-src=\"https:\/\/old.badiofreelance.com\/wp-content\/uploads\/2022\/10\/Untitled-design-4-720x405.jpg\" \/>\n\t\t\t\t\t\t<\/a>\n\n\t\t\t\t\t\t\n\t\t\t\t\t\t<a href=\"https:\/\/old.badiofreelance.com\/nl\/job\/programming-tech\/i-will-build-wordpress-ecommerce-website-using-woocommerce\/\" class=\"slide-img\">\n\t\t\t\t\t\t\t<img src=\"https:\/\/old.badiofreelance.com\/wp-content\/themes\/wpjobster\/assets\/images\/media\/blank.gif\" class=\"job-blurry-bg bx-lazy owl-lazy\" data-src=\"https:\/\/old.badiofreelance.com\/wp-content\/uploads\/2022\/10\/Untitled-design-6-720x405.png\" \/>\n\t\t\t\t\t\t\t<img src=\"https:\/\/old.badiofreelance.com\/wp-content\/themes\/wpjobster\/assets\/images\/media\/blank.gif\" class=\"bx-lazy owl-lazy\" data-src=\"https:\/\/old.badiofreelance.com\/wp-content\/uploads\/2022\/10\/Untitled-design-6-720x405.png\" \/>\n\t\t\t\t\t\t<\/a>\n\n\t\t\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\n\t<\/div>\n\n\t<!-- User -->\n\t<div class=\"user-area\">\n\n\t\t<!-- User Avatar -->\n\t\t<div class=\"user-avatar\">\n\n\t\t\t\n\t<a class=\"pr user-avatar-image\" href=\"https:\/\/old.badiofreelance.com\/nl\/user\/Rakib\/\">\n\n\n\t\t<img class=\"round-avatar\" width=\"55\" height=\"55\" src=\"https:\/\/old.badiofreelance.com\/wp-content\/uploads\/secure\/2022\/10\/vecteezy_flower_1190269-150x150.png\" \/>\n\n\t\t\n\t<\/a>\n\n\n\t\t<\/div>\n\n\t\t<!-- Username & Level -->\n\t\t<div class=\"user-content\">\n\t\t\t<a href=\"https:\/\/old.badiofreelance.com\/nl\/user\/Rakib\/\" class=\"cards-user-link\">\n\n\t\t\t\t<!-- Name -->\n\t\t\t\t<div class=\"user-name\">Rakib<\/div>\n\n\t\t\t\t<!-- Level -->\n\t\t\t\t\n\t<span class=\"user-level-label user-level-label-0\">New Arrival<\/span>\n\n\n\t\t\t<\/a>\n\t\t<\/div>\n\n\t\t<!-- Rating after user details -->\n\t\t\n\t\t\t\t<div class=\"user-rating\">\n\n\t\t\t\t\t<div class=\"wpj-rating-single\">\n\n\t\t\t\t\t\t<i class=\"star icon static\"><\/i>\n\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t<span class=\"rating-score\"><strong>0<\/strong><\/span>\n\t\t\t\t\t\t\t<span class=\"rating-reviews-number\">(0)<\/span>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t<\/div>\n\n\t\t\t\n\t<\/div>\n\n\t<!-- Title -->\n\t<div class=\"job-area\">\n\t\t<a class=\"title list-header\" href=\"https:\/\/old.badiofreelance.com\/nl\/job\/programming-tech\/i-will-build-wordpress-ecommerce-website-using-woocommerce\/\" title=\"\">Ik zal een WordPress e-commerce website bouwen met behulp van woocommerce<\/a>\n\n\t\t<div class=\"description visible-on-list\">\n\n\t\t\tHet is erg belangrijk om de behoeften, vereisten en problemen te begrijpen als ik moet bellen. Met de ontwikkeling van WordPress gedurende meer dan 1 jaar, heeft mijn woocommerce website-expert 100 thema&#039;s en...\n\t\t<\/div>\n\n\t\t<!-- Rating after title -->\n\t\t\n\t<\/div>\n\n\t<!-- Price & Let's Meet & Favorites -->\n\t<div class=\"job-bottom-info\">\n\t\t<div class=\"job-price-area\">\n\n\t\t\t<!-- Price -->\n\t\t\t<div class=\"job-price\">\n\n\t\t\t\t\n\t\t\t\t\t<div class=\"price-type\">Starting at<\/div>\n\t\t\t\t\t<div class=\"price\">$60.00<\/div>\n\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\t<div class=\"card-icons one-item\">\n\t\t\n\t\t\t\t<!-- Instant Delivery -->\n\t\t\t\t\n\t\t\t\t<!-- Let's Meet -->\n\t\t\t\t\n\t\t\t\t<!-- Distance -->\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t<\/div>\n\n\t\t<!-- Favorites -->\n\t\t<div class=\"job-favorites\">\n\n\t\t\t<div data-inverted=\"\" data-tooltip=\"Favorites\" data-position=\"top center\">\n\n\t\t\t\t\n\t<div class=\"upb_add_remove_links\">\n\n\t\t<a href=\"https:\/\/old.badiofreelance.com\/nl\/authentication-login\/?redirect_to=https%3A%2F%2Fold.badiofreelance.com%2Fnl%2Fsearch-jobs%2F\" rel=\"23628\" class=\"login-link\">\n\t\t\t<div class=\"empty-heart\"><\/div>\n\t\t\t<span>\n\t\t\t\t<div class=\"\">\n\t\t\t\t\t<span><i class=\"heart outline grey icon\"><\/i><\/span>\n\t\t\t\t<\/div>\n\t\t\t<\/span>\n\t\t<\/a>\n\n\t<\/div>\n\n\n\t\t\t<\/div>\n\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><!-- Job Card -->\n<div class=\"job-card ui card wpj-card-style-3 extra-slider-height\">\n\n\t<!-- Job Image -->\n\t<div class=\"image\">\n\n\t\t<!-- Featured -->\n\t\t\n\t\t<!-- Show until slider, load then remove -->\n\t\t<div class=\"card-image-clipper\">\n\t\t\t<div class=\"card-image-helper\">\n\t\t\t\t<img class=\"card-blurry-bg\" src=\"https:\/\/old.badiofreelance.com\/wp-content\/uploads\/2022\/10\/image-2.png\" alt=\"23667Search Jobs\" \/>\n\t\t\t\t<img class=\"my_image\" src=\"https:\/\/old.badiofreelance.com\/wp-content\/uploads\/2022\/10\/image-2.png\" alt=\"23667Search Jobs\" \/>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t<!-- Show slider -->\n\t\t\n\t\t\t<div class=\"wpj-carousel owl-carousel owl-theme\">\n\n\t\t\t\t\n\t\t\t\t\t\t<a href=\"https:\/\/old.badiofreelance.com\/nl\/job\/e-commerce-development\/i-will-build-ecommerce-online-store-website-using-woocommerce\/\" class=\"slide-img\">\n\t\t\t\t\t\t\t<img src=\"https:\/\/old.badiofreelance.com\/wp-content\/uploads\/2022\/10\/image-2-720x405.png\" class=\"job-blurry-bg\" data-src=\"https:\/\/old.badiofreelance.com\/wp-content\/uploads\/2022\/10\/image-2-720x405.png\" \/>\n\t\t\t\t\t\t\t<img src=\"https:\/\/old.badiofreelance.com\/wp-content\/uploads\/2022\/10\/image-2-720x405.png\" class=\"\" data-src=\"https:\/\/old.badiofreelance.com\/wp-content\/uploads\/2022\/10\/image-2-720x405.png\" \/>\n\t\t\t\t\t\t<\/a>\n\n\t\t\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\n\t<\/div>\n\n\t<!-- User -->\n\t<div class=\"user-area\">\n\n\t\t<!-- User Avatar -->\n\t\t<div class=\"user-avatar\">\n\n\t\t\t\n\t<a class=\"pr user-avatar-image\" href=\"https:\/\/old.badiofreelance.com\/nl\/user\/papanbiswasbd\/\">\n\n\n\t\t<img class=\"round-avatar\" width=\"55\" height=\"55\" src=\"https:\/\/secure.gravatar.com\/avatar\/ec14db33440bd1930327216fbaa11d64?s=55&d=mm&r=g\" \/>\n\n\t\t\n\t<\/a>\n\n\n\t\t<\/div>\n\n\t\t<!-- Username & Level -->\n\t\t<div class=\"user-content\">\n\t\t\t<a href=\"https:\/\/old.badiofreelance.com\/nl\/user\/papanbiswasbd\/\" class=\"cards-user-link\">\n\n\t\t\t\t<!-- Name -->\n\t\t\t\t<div class=\"user-name\">papanbiswasbd<\/div>\n\n\t\t\t\t<!-- Level -->\n\t\t\t\t\n\t<span class=\"user-level-label user-level-label-0\">New Arrival<\/span>\n\n\n\t\t\t<\/a>\n\t\t<\/div>\n\n\t\t<!-- Rating after user details -->\n\t\t\n\t\t\t\t<div class=\"user-rating\">\n\n\t\t\t\t\t<div class=\"wpj-rating-single\">\n\n\t\t\t\t\t\t<i class=\"star icon static\"><\/i>\n\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t<span class=\"rating-score\"><strong>0<\/strong><\/span>\n\t\t\t\t\t\t\t<span class=\"rating-reviews-number\">(0)<\/span>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t<\/div>\n\n\t\t\t\n\t<\/div>\n\n\t<!-- Title -->\n\t<div class=\"job-area\">\n\t\t<a class=\"title list-header\" href=\"https:\/\/old.badiofreelance.com\/nl\/job\/e-commerce-development\/i-will-build-ecommerce-online-store-website-using-woocommerce\/\" title=\"\">Ik zal een e-commerce online winkelwebsite bouwen met behulp van woocommerce<\/a>\n\n\t\t<div class=\"description visible-on-list\">\n\n\t\t\t\u2705 Bent u op zoek naar een professionele WooCommerce-website? \u2705 Als u een eCommerce, Multivendor Online Store of WooCommerce Website voor uw bedrijf wilt bouwen. Ik ben de beste keuze voor jou. Uw...\n\t\t<\/div>\n\n\t\t<!-- Rating after title -->\n\t\t\n\t<\/div>\n\n\t<!-- Price & Let's Meet & Favorites -->\n\t<div class=\"job-bottom-info\">\n\t\t<div class=\"job-price-area\">\n\n\t\t\t<!-- Price -->\n\t\t\t<div class=\"job-price\">\n\n\t\t\t\t\n\t\t\t\t\t<div class=\"price-type\">Starting at<\/div>\n\t\t\t\t\t<div class=\"price\">$80.00<\/div>\n\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\t<div class=\"card-icons one-item\">\n\t\t\n\t\t\t\t<!-- Instant Delivery -->\n\t\t\t\t\n\t\t\t\t<!-- Let's Meet -->\n\t\t\t\t\n\t\t\t\t\t<div class=\"job-lets-meet\" data-inverted=\"\" data-tooltip=\"Let's meet\" data-position=\"top center\">\n\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t<i class=\"icon icon-img\"><img src=\"https:\/\/old.badiofreelance.com\/wp-content\/themes\/wpjobster\/assets\/images\/card\/location-icon.svg\" alt=\"\"><\/i>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\n\t\t\t\t<!-- Distance -->\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t<\/div>\n\n\t\t<!-- Favorites -->\n\t\t<div class=\"job-favorites\">\n\n\t\t\t<div data-inverted=\"\" data-tooltip=\"Favorites\" data-position=\"top center\">\n\n\t\t\t\t\n\t<div class=\"upb_add_remove_links\">\n\n\t\t<a href=\"https:\/\/old.badiofreelance.com\/nl\/authentication-login\/?redirect_to=https%3A%2F%2Fold.badiofreelance.com%2Fnl%2Fsearch-jobs%2F\" rel=\"23667\" class=\"login-link\">\n\t\t\t<div class=\"empty-heart\"><\/div>\n\t\t\t<span>\n\t\t\t\t<div class=\"\">\n\t\t\t\t\t<span><i class=\"heart outline grey icon\"><\/i><\/span>\n\t\t\t\t<\/div>\n\t\t\t<\/span>\n\t\t<\/a>\n\n\t<\/div>\n\n\n\t\t\t<\/div>\n\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><!-- Job Card -->\n<div class=\"job-card ui card wpj-card-style-3 extra-slider-height\">\n\n\t<!-- Job Image -->\n\t<div class=\"image\">\n\n\t\t<!-- Featured -->\n\t\t\n\t\t<!-- Show until slider, load then remove -->\n\t\t<div class=\"card-image-clipper\">\n\t\t\t<div class=\"card-image-helper\">\n\t\t\t\t<img class=\"card-blurry-bg\" src=\"https:\/\/old.badiofreelance.com\/wp-content\/uploads\/2022\/10\/4428861-1-scaled.jpg\" alt=\"24195Search Jobs\" \/>\n\t\t\t\t<img class=\"my_image\" src=\"https:\/\/old.badiofreelance.com\/wp-content\/uploads\/2022\/10\/4428861-1-scaled.jpg\" alt=\"24195Search Jobs\" \/>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t<!-- Show slider -->\n\t\t\n\t\t\t<div class=\"wpj-carousel owl-carousel owl-theme\">\n\n\t\t\t\t\n\t\t\t\t\t\t<a href=\"https:\/\/old.badiofreelance.com\/nl\/job\/mobile-apps\/i-will-build-your-android-source-code-and-publish-your-app-in-play-store\/\" class=\"slide-img\">\n\t\t\t\t\t\t\t<img src=\"https:\/\/old.badiofreelance.com\/wp-content\/uploads\/2022\/10\/4428861-1-608x405.jpg\" class=\"job-blurry-bg\" data-src=\"https:\/\/old.badiofreelance.com\/wp-content\/uploads\/2022\/10\/4428861-1-608x405.jpg\" \/>\n\t\t\t\t\t\t\t<img src=\"https:\/\/old.badiofreelance.com\/wp-content\/uploads\/2022\/10\/4428861-1-608x405.jpg\" class=\"\" data-src=\"https:\/\/old.badiofreelance.com\/wp-content\/uploads\/2022\/10\/4428861-1-608x405.jpg\" \/>\n\t\t\t\t\t\t<\/a>\n\n\t\t\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\n\t<\/div>\n\n\t<!-- User -->\n\t<div class=\"user-area\">\n\n\t\t<!-- User Avatar -->\n\t\t<div class=\"user-avatar\">\n\n\t\t\t\n\t<a class=\"pr user-avatar-image\" href=\"https:\/\/old.badiofreelance.com\/nl\/user\/marufshah\/\">\n\n\n\t\t<img class=\"round-avatar\" width=\"55\" height=\"55\" src=\"https:\/\/secure.gravatar.com\/avatar\/d50ff3010d2322d8b612cf5bd7f0c0e6?s=55&d=mm&r=g\" \/>\n\n\t\t\n\t<\/a>\n\n\n\t\t<\/div>\n\n\t\t<!-- Username & Level -->\n\t\t<div class=\"user-content\">\n\t\t\t<a href=\"https:\/\/old.badiofreelance.com\/nl\/user\/marufshah\/\" class=\"cards-user-link\">\n\n\t\t\t\t<!-- Name -->\n\t\t\t\t<div class=\"user-name\">marufshah<\/div>\n\n\t\t\t\t<!-- Level -->\n\t\t\t\t\n\t<span class=\"user-level-label user-level-label-0\">New Arrival<\/span>\n\n\n\t\t\t<\/a>\n\t\t<\/div>\n\n\t\t<!-- Rating after user details -->\n\t\t\n\t\t\t\t<div class=\"user-rating\">\n\n\t\t\t\t\t<div class=\"wpj-rating-single\">\n\n\t\t\t\t\t\t<i class=\"star icon static\"><\/i>\n\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t<span class=\"rating-score\"><strong>0<\/strong><\/span>\n\t\t\t\t\t\t\t<span class=\"rating-reviews-number\">(0)<\/span>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t<\/div>\n\n\t\t\t\n\t<\/div>\n\n\t<!-- Title -->\n\t<div class=\"job-area\">\n\t\t<a class=\"title list-header\" href=\"https:\/\/old.badiofreelance.com\/nl\/job\/mobile-apps\/i-will-build-your-android-source-code-and-publish-your-app-in-play-store\/\" title=\"\">Ik bouw je Android-broncode en publiceer je app in...<\/a>\n\n\t\t<div class=\"description visible-on-list\">\n\n\t\t\tWij lossen al uw problemen op. Als je een console hebt, publiceren we de app via deze. Indien nodig helpen we je bij het opzetten van een nieuwe console. Wat we nodig hebben om uw app op Google Play te publiceren...\n\t\t<\/div>\n\n\t\t<!-- Rating after title -->\n\t\t\n\t<\/div>\n\n\t<!-- Price & Let's Meet & Favorites -->\n\t<div class=\"job-bottom-info\">\n\t\t<div class=\"job-price-area\">\n\n\t\t\t<!-- Price -->\n\t\t\t<div class=\"job-price\">\n\n\t\t\t\t\n\t\t\t\t\t<div class=\"price-type\">Starting at<\/div>\n\t\t\t\t\t<div class=\"price\">$20.00<\/div>\n\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\t<div class=\"card-icons one-item\">\n\t\t\n\t\t\t\t<!-- Instant Delivery -->\n\t\t\t\t\n\t\t\t\t<!-- Let's Meet -->\n\t\t\t\t\n\t\t\t\t<!-- Distance -->\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t<\/div>\n\n\t\t<!-- Favorites -->\n\t\t<div class=\"job-favorites\">\n\n\t\t\t<div data-inverted=\"\" data-tooltip=\"Favorites\" data-position=\"top center\">\n\n\t\t\t\t\n\t<div class=\"upb_add_remove_links\">\n\n\t\t<a href=\"https:\/\/old.badiofreelance.com\/nl\/authentication-login\/?redirect_to=https%3A%2F%2Fold.badiofreelance.com%2Fnl%2Fsearch-jobs%2F\" rel=\"24195\" class=\"login-link\">\n\t\t\t<div class=\"empty-heart\"><\/div>\n\t\t\t<span>\n\t\t\t\t<div class=\"\">\n\t\t\t\t\t<span><i class=\"heart outline grey icon\"><\/i><\/span>\n\t\t\t\t<\/div>\n\t\t\t<\/span>\n\t\t<\/a>\n\n\t<\/div>\n\n\n\t\t\t<\/div>\n\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><!-- Job Card -->\n<div class=\"job-card ui card wpj-card-style-3 extra-slider-height\">\n\n\t<!-- Job Image -->\n\t<div class=\"image\">\n\n\t\t<!-- Featured -->\n\t\t\n\t\t<!-- Show until slider, load then remove -->\n\t\t<div class=\"card-image-clipper\">\n\t\t\t<div class=\"card-image-helper\">\n\t\t\t\t<img class=\"card-blurry-bg\" src=\"https:\/\/old.badiofreelance.com\/wp-content\/uploads\/2022\/10\/image-2-1.png\" alt=\"24383Search Jobs\" \/>\n\t\t\t\t<img class=\"my_image\" src=\"https:\/\/old.badiofreelance.com\/wp-content\/uploads\/2022\/10\/image-2-1.png\" alt=\"24383Search Jobs\" \/>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t<!-- Show slider -->\n\t\t\n\t\t\t<div class=\"wpj-carousel owl-carousel owl-theme\">\n\n\t\t\t\t\n\t\t\t\t\t\t<a href=\"https:\/\/old.badiofreelance.com\/nl\/job\/e-commerce-development\/i-will-build-ecommerce-online-store-website-using-woocommerce-milestone\/\" class=\"slide-img\">\n\t\t\t\t\t\t\t<img src=\"https:\/\/old.badiofreelance.com\/wp-content\/uploads\/2022\/10\/image-2-1-720x405.png\" class=\"job-blurry-bg\" data-src=\"https:\/\/old.badiofreelance.com\/wp-content\/uploads\/2022\/10\/image-2-1-720x405.png\" \/>\n\t\t\t\t\t\t\t<img src=\"https:\/\/old.badiofreelance.com\/wp-content\/uploads\/2022\/10\/image-2-1-720x405.png\" class=\"\" data-src=\"https:\/\/old.badiofreelance.com\/wp-content\/uploads\/2022\/10\/image-2-1-720x405.png\" \/>\n\t\t\t\t\t\t<\/a>\n\n\t\t\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\n\t<\/div>\n\n\t<!-- User -->\n\t<div class=\"user-area\">\n\n\t\t<!-- User Avatar -->\n\t\t<div class=\"user-avatar\">\n\n\t\t\t\n\t<a class=\"pr user-avatar-image\" href=\"https:\/\/old.badiofreelance.com\/nl\/user\/papanbiswasbd\/\">\n\n\n\t\t<img class=\"round-avatar\" width=\"55\" height=\"55\" src=\"https:\/\/secure.gravatar.com\/avatar\/ec14db33440bd1930327216fbaa11d64?s=55&d=mm&r=g\" \/>\n\n\t\t\n\t<\/a>\n\n\n\t\t<\/div>\n\n\t\t<!-- Username & Level -->\n\t\t<div class=\"user-content\">\n\t\t\t<a href=\"https:\/\/old.badiofreelance.com\/nl\/user\/papanbiswasbd\/\" class=\"cards-user-link\">\n\n\t\t\t\t<!-- Name -->\n\t\t\t\t<div class=\"user-name\">papanbiswasbd<\/div>\n\n\t\t\t\t<!-- Level -->\n\t\t\t\t\n\t<span class=\"user-level-label user-level-label-0\">New Arrival<\/span>\n\n\n\t\t\t<\/a>\n\t\t<\/div>\n\n\t\t<!-- Rating after user details -->\n\t\t\n\t\t\t\t<div class=\"user-rating\">\n\n\t\t\t\t\t<div class=\"wpj-rating-single\">\n\n\t\t\t\t\t\t<i class=\"star icon static\"><\/i>\n\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t<span class=\"rating-score\"><strong>0<\/strong><\/span>\n\t\t\t\t\t\t\t<span class=\"rating-reviews-number\">(0)<\/span>\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t<\/div>\n\n\t\t\t\n\t<\/div>\n\n\t<!-- Title -->\n\t<div class=\"job-area\">\n\t\t<a class=\"title list-header\" href=\"https:\/\/old.badiofreelance.com\/nl\/job\/e-commerce-development\/i-will-build-ecommerce-online-store-website-using-woocommerce-milestone\/\" title=\"\">Ik zal een e-commerce online winkelwebsite bouwen met behulp van woocommerce...<\/a>\n\n\t\t<div class=\"description visible-on-list\">\n\n\t\t\tDit is testen ldsjfg asldkf jkasdjl fakls;df jasdlj hfl;sdaffjaksdjh f;oasdfjkgkjadsfh g;oidfz&nbsp;\n\t\t<\/div>\n\n\t\t<!-- Rating after title -->\n\t\t\n\t<\/div>\n\n\t<!-- Price & Let's Meet & Favorites -->\n\t<div class=\"job-bottom-info\">\n\t\t<div class=\"job-price-area\">\n\n\t\t\t<!-- Price -->\n\t\t\t<div class=\"job-price\">\n\n\t\t\t\t\n\t\t\t\t\t<div class=\"price-type\">milestone rate<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"price\">$500.00<\/div>\n\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\t<div class=\"card-icons one-item\">\n\t\t\n\t\t\t\t<!-- Instant Delivery -->\n\t\t\t\t\n\t\t\t\t<!-- Let's Meet -->\n\t\t\t\t\n\t\t\t\t<!-- Distance -->\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t<\/div>\n\n\t\t<!-- Favorites -->\n\t\t<div class=\"job-favorites\">\n\n\t\t\t<div data-inverted=\"\" data-tooltip=\"Favorites\" data-position=\"top center\">\n\n\t\t\t\t\n\t<div class=\"upb_add_remove_links\">\n\n\t\t<a href=\"https:\/\/old.badiofreelance.com\/nl\/authentication-login\/?redirect_to=https%3A%2F%2Fold.badiofreelance.com%2Fnl%2Fsearch-jobs%2F\" rel=\"24383\" class=\"login-link\">\n\t\t\t<div class=\"empty-heart\"><\/div>\n\t\t\t<span>\n\t\t\t\t<div class=\"\">\n\t\t\t\t\t<span><i class=\"heart outline grey icon\"><\/i><\/span>\n\t\t\t\t<\/div>\n\t\t\t<\/span>\n\t\t<\/a>\n\n\t<\/div>\n\n\n\t\t\t<\/div>\n\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\n<\/div>\n<\/div><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n<\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Geavanceerd zoeken naar vacatures<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":""},"acf":[],"featured_image_src_large":false,"author_info":{"display_name":"Badio Freelance","author_link":"https:\/\/old.badiofreelance.com\/nl\/author\/supportsurruplatform-com\/"},"comment_info":0,"taxonomy_info":[],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"trp-custom-language-flag":false,"thumb_picture_size":false,"job_cover_image":false,"job_slider_image":false,"blog_thumbnail_big":false,"news_slider":false,"square_150":false,"square_180":false},"uagb_author_info":{"display_name":"Badio Freelance","author_link":"https:\/\/old.badiofreelance.com\/nl\/author\/supportsurruplatform-com\/"},"uagb_comment_info":0,"uagb_excerpt":"Advanced search for jobs","_links":{"self":[{"href":"https:\/\/old.badiofreelance.com\/nl\/wp-json\/wp\/v2\/pages\/27"}],"collection":[{"href":"https:\/\/old.badiofreelance.com\/nl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/old.badiofreelance.com\/nl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/old.badiofreelance.com\/nl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/old.badiofreelance.com\/nl\/wp-json\/wp\/v2\/comments?post=27"}],"version-history":[{"count":0,"href":"https:\/\/old.badiofreelance.com\/nl\/wp-json\/wp\/v2\/pages\/27\/revisions"}],"wp:attachment":[{"href":"https:\/\/old.badiofreelance.com\/nl\/wp-json\/wp\/v2\/media?parent=27"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}